{"id":50215,"date":"2012-06-28T14:22:25","date_gmt":"2012-06-28T13:22:25","guid":{"rendered":"https:\/\/www.xjtag.com\/case-studies\/saab-case-study-es\/"},"modified":"2025-02-24T11:30:43","modified_gmt":"2025-02-24T11:30:43","slug":"saab-case-study-es","status":"publish","type":"case_studies","link":"https:\/\/www.xjtag.com\/es\/case-studies\/saab-case-study-es\/","title":{"rendered":"Saab reduce costes y aumenta la productividad con XJTAG \u201cboundary scan\u201d"},"content":{"rendered":"<p>Saab, un compa\u00f1\u00eda de Defensa y Seguridad, seleccion\u00f3 el sistema de desarrollo XJTAG para acelerar el proceso de depuraci\u00f3n y test de tarjetas PCBs multicapa de desarrollo, destinadas a sus proyectos IDAS y CIDAS, utilizados en sistemas de guerra electr\u00f3nica.<\/p>\n<p>Saab suministra al mercado global con soluciones avanzadas, productos y servicios l\u00edderes en el mundo que van desde la defensa militar para la seguridad civil. Con operaciones y empleados en todos los continentes, Saab desarrolla de manera continua, adapta y mejora la nueva tecnolog\u00eda para satisfacer las necesidades cambiantes de los clientes. Saab opera en cinco \u00e1reas de negocio: Aeron\u00e1utica, Din\u00e1mica, Sistemas Electr\u00f3nicas de Defensa, Soluciones de Seguridad y Defensa, y de Soporte y Servicios.<\/p>\n<p>La versatilidad del sistema XJTAG hizo una opci\u00f3n atractiva para Saab, l\u00edder mundial en defensa y especialista en seguridad, que necesitaba una soluci\u00f3n de test fiable para probar tarjetas PCB de desarrollo multicapa destinadas a los sistemas electr\u00f3nicos de guerra a\u00e9rea y naval utilizados en sus productos IDAS y CIDAS.<\/p>\n<p>\u201cHemos utilizado XJTAG inicialmente en el entorno de producci\u00f3n para poner a test nuestros dise\u00f1os de placas complejos, de alta densidad y de varias capas, que contienen componentes FPGA y CPLD. Recientemente hemos introducido la soluci\u00f3n para el desarrollo y la etapa de depuraci\u00f3n con gran \u00e9xito\u201d, dice Eduard Stander, que trabaja para el Grupo de Controladores en los Sistemas Electr\u00f3nicos de Defensa de Saab, en Sud\u00e1frica.<\/p>\n<p>\u201cEl uso de la aplicaci\u00f3n XJAnalyser, nos ha permitido reducir los problemas iniciales de depuraci\u00f3n y depurar errores en un tiempo m\u00e1s corto que con nuestras herramientas existentes\u201d.<\/p>\n<p>\u201cHemos encontrado que el uso de la soluci\u00f3n XJTAG, y en particular de el \u201cLayout Viewer\u201d, ha reducido cuantitativamente el costo de desarrollar \u201ctest jigs\u201d del producto en nuestro departamento de tests de producci\u00f3n, debido al diagn\u00f3stico r\u00e1pido y preciso que el sistema ofrece.\u201d \u201cAhora podemos probar productos que tienen procesadores, memorias SDRAM y FLASH, PHY de Ethernet, conversores A \/ D, los relojes en tiempo real, puertos serie y reguladores de tensi\u00f3n.\u201d<\/p>\n<p>El equipo de Saab ha optado por XJTAG debido a su excelente relaci\u00f3n coste-rendimiento y igual que muchos de los clientes XJTAG, estaban particularmente impresionados con la flexibilidad del sistema.<\/p>\n<p>XJTAG hace que sea f\u00e1cil escribir rutinas de test para los componentes y permite a los usuarios salvarlos en una librer\u00eda para que puedan ser reutilizados de nuevo cuando el mismo componente o uno similar se utiliza.<\/p>\n<p>El Sistema de \u201cXJTAG Professional\u201d\u00a0 proporciona una amplia librer\u00eda de scripts reutilizables mientras que, XJEase, el lenguaje de alto nivel de descripci\u00f3n de test de XJTAG, permite a los ingenieros escribir y personalizar los tests de componentes JTAG y no-JTAG, sin necesidad de entender c\u00f3mo funciona el \u201cboundary scan\u201d. Estas pruebas pueden ser<br \/>\nre-utilizadas en todo el ciclo de vida del producto, as\u00ed como en proyectos posteriores dondequiera que el mismo componente se utiliza.<\/p>\n<p>\u201cLa reutilizaci\u00f3n de los tests en el sistema XJTAG es un gran ahorro de tiempo\u201d, dice Eduard. \u201cLos informes DFT (Design For Test o Dise\u00f1o para Testabilidad), nos ayudan a garantizar que un porcentaje muy alto de nuestros circuitos son testeables antes de entrar en producci\u00f3n en serie y, con la ayuda de pruebas \u201cboundary scan\u201d, nos acercamos a nuestra meta de cobertura de test del 100% en las unidades de producci\u00f3n SRU (Shop Replaceable Units).\u201d<\/p>\n<p>Y a\u00f1ade: \u201cXJEase, el lenguaje de alto nivel de descripci\u00f3n de test de XJTAG es fundamental para esta flexibilidad. La capacidad de dise\u00f1ar los tests de bajo nivel con XJEase es una gran ventaja ya que los scripts de test permiten llegar a los componentes no-JTAG directamente.\u201d<\/p>\n<p>Eduard dice el siguiente paso de la compa\u00f1\u00eda es la integraci\u00f3n del producto portable de osciloscopio \u201cboundary scan\u201d de XJTAG \u2013 llamado XJTAG Expert \u2013 con su equipo de pruebas funcionales. \u201cXJTAG es f\u00e1cil de usar, muy eficaz y suficientemente flexible como para evolucionar con nuestras estrategias de test a medida que se centran en mejorar la velocidad y la productividad.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Defence and Security company Saab cuts costs and boosts productivity with XJTAG boundary scan<\/p>\n","protected":false},"author":1577,"featured_media":41449,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"caseindustry":[137],"caselanguage":[179,171,174,175],"caselocation":[240,242],"caseusecases":[124,216,123,125,219],"product":[54,161,156],"class_list":["post-50215","case_studies","type-case_studies","status-publish","has-post-thumbnail","hentry","caseindustry-defense-millitary-government","caselanguage-english-a4","caselanguage-spanish","caselanguage-italian","caselanguage-japanese","caselocation-south-africa","caselocation-sweden","caseusecases-circuit-visualisation","caseusecases-design-for-test","caseusecases-fault-diagnosis","caseusecases-design-verification","caseusecases-test-coverage-analysis","product-xjanalyser","product-xjapi-interface","product-xjtag-expert"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.xjtag.com\/es\/wp-json\/wp\/v2\/case_studies\/50215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.xjtag.com\/es\/wp-json\/wp\/v2\/case_studies"}],"about":[{"href":"https:\/\/www.xjtag.com\/es\/wp-json\/wp\/v2\/types\/case_studies"}],"author":[{"embeddable":true,"href":"https:\/\/www.xjtag.com\/es\/wp-json\/wp\/v2\/users\/1577"}],"version-history":[{"count":0,"href":"https:\/\/www.xjtag.com\/es\/wp-json\/wp\/v2\/case_studies\/50215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.xjtag.com\/es\/wp-json\/wp\/v2\/media\/41449"}],"wp:attachment":[{"href":"https:\/\/www.xjtag.com\/es\/wp-json\/wp\/v2\/media?parent=50215"}],"wp:term":[{"taxonomy":"caseindustry","embeddable":true,"href":"https:\/\/www.xjtag.com\/es\/wp-json\/wp\/v2\/caseindustry?post=50215"},{"taxonomy":"caselanguage","embeddable":true,"href":"https:\/\/www.xjtag.com\/es\/wp-json\/wp\/v2\/caselanguage?post=50215"},{"taxonomy":"caselocation","embeddable":true,"href":"https:\/\/www.xjtag.com\/es\/wp-json\/wp\/v2\/caselocation?post=50215"},{"taxonomy":"caseusecases","embeddable":true,"href":"https:\/\/www.xjtag.com\/es\/wp-json\/wp\/v2\/caseusecases?post=50215"},{"taxonomy":"product","embeddable":true,"href":"https:\/\/www.xjtag.com\/es\/wp-json\/wp\/v2\/product?post=50215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}